{"id":128593,"date":"2026-05-15T13:13:12","date_gmt":"2026-05-15T11:13:12","guid":{"rendered":"https:\/\/cambrabcn.org\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/"},"modified":"2026-05-20T12:58:54","modified_gmt":"2026-05-20T10:58:54","slug":"mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru","status":"publish","type":"press-release","link":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/","title":{"rendered":"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La cuarta edici\u00f3n de la feria de la ocupaci\u00f3n <strong>GiraFeina<\/strong> ha cerrado con <strong>726 asistentes<\/strong> y la participaci\u00f3n de <strong>26 empresas<\/strong>, que han ofrecido 113 ofertas de trabajo con un total de 398 vacantes laborales.<\/p>\n\n<p class=\"wp-block-paragraph\">La jornada se ha consolidando como un <strong>espacio clave para impulsar la ocupaci\u00f3n y dinamizar el mercado laboral en el Garraf<\/strong>. Del total de participantes, 271 eran j\u00f3venes menores de 30 a\u00f1os, hecho que evidencia tambi\u00e9n el papel de la feria como herramienta para <strong>potenciar el talento joven<\/strong> y facilitar la inserci\u00f3n laboral.<\/p>\n\n<p class=\"wp-block-paragraph\">Durante el acontecimiento se han llevado a cabo <strong>1.275 entrevistas<\/strong> de trabajo a trav\u00e9s de un formato breve, tipo <em>speed dating<\/em>, que facilita el contacto directo entre empresas locales y personas en b\u00fasqueda activa de nuevas oportunidades profesionales.<\/p>\n\n<p class=\"wp-block-paragraph\">La iniciativa ha tenido lugar este jueves 14 de mayo en el <strong>edificio Ne\u00e0polis de Vilanova i la Geltr\u00fa<\/strong>, que ha acogido los diferentes espacios de la jornada, combinando entrevistas laborales con actividades de apoyo a la ocupaci\u00f3n, charlas, puntos de orientaci\u00f3n laboral y muestras de oficios.<\/p>\n\n<h6 class=\"wp-block-heading\" id=\"h-orientacio-entrevistes-i-tastets-d-oficis-per-impulsar-l-ocupacio\"><strong>Orientaci\u00f3n, entrevistas y muestras de oficios para impulsar la ocupaci\u00f3n<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">La GiraFeina de Vilanova i la Geltr\u00fa 2026 ha contado con diferentes espacios destinados a ofrecer a los participantes recursos pr\u00e1cticos para la investigaci\u00f3n de trabajo, la orientaci\u00f3n profesional y el contacto directo con el tejido empresarial del territorio.<\/p>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del <strong>Espacio Empresas<\/strong>, donde se han realizado las entrevistas a los candidatos y candidatas y que se ha llenado desde primera hora de la ma\u00f1ana, este a\u00f1o ha destacado especialmente el <strong>Espacio Charlas<\/strong>, que ha acogido con gran \u00e9xito de asistencia un total de ocho sesiones sobre ocupaci\u00f3n, orientaci\u00f3n laboral y sectores profesionales, con la participaci\u00f3n de diferentes gremios y entidades del territorio. Entre las actividades programadas, tambi\u00e9n se ha presentado el <strong>Programa Incorpora<\/strong>, orientado a facilitar la inserci\u00f3n laboral de personas con m\u00e1s dificultades de acceso al mercado de trabajo.<\/p>\n\n<p class=\"wp-block-paragraph\">El espacio <strong>Muestras de Oficios<\/strong> tambi\u00e9n ha tenido muy buena acogida, puesto que los participantes han podido experimentar de manera pr\u00e1ctica diversas profesiones y conocer habilidades vinculadas al mundo laboral.<\/p>\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, el <strong>Espacio Orientaci\u00f3n<\/strong>, formado por seis carpas especializadas, se ha consolidado como un punto clave para ofrecer asesoramiento personalizado y recursos para la investigaci\u00f3n de trabajo y el autoempleo, as\u00ed como para el acompa\u00f1amiento en el desarrollo profesional de los participantes.<\/p>\n\n<h6 class=\"wp-block-heading\" id=\"h-una-edicio-marcada-pel-creixement-de-la-participacio-i-el-dinamisme-de-la-jornada\"><strong>Una edici\u00f3n marcada por el crecimiento de la participaci\u00f3n y el dinamismo de la jornada<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">La buena respuesta de empresas y personas asistentes consolida la GiraFeina de Vilanova i la Geltr\u00fa como una <strong>iniciativa de referencia en el \u00e1mbito de la ocupaci\u00f3n en el territorio<\/strong>. Esta cuarta edici\u00f3n ha mejorado las cifras de participaci\u00f3n del a\u00f1o pasado, superando los 700 asistentes e incrementando tambi\u00e9n el volumen de entrevistas laborales realizadas durante la jornada.<\/p>\n\n<p class=\"wp-block-paragraph\">El presidente de la Cambra de Comer\u00e7 de Barcelona en el Garraf, <strong>Xavier Montserrat<\/strong>, ha celebrado el \u00e9xito de la iniciativa, tanto en cuanto al volumen de interacciones con la empresa como en las actividades organizadas. \u201cMuchos candidatos y candidatas, muchas entrevistas, en un espacio excelente como es el Ne\u00e0polis, por la buena ubicaci\u00f3n que ha ofrecido en todos los espacios\u201d, ha subrayado Montserrat.<\/p>\n\n<p class=\"wp-block-paragraph\">El \u00e9xito de la feria refuerza la voluntad de las entidades organizadoras de <strong>continuar apostando por la GiraFeina como una herramienta estrat\u00e9gica<\/strong> para fomentar la ocupaci\u00f3n, la inclusi\u00f3n laboral y el desarrollo econ\u00f3mico local, as\u00ed como para reforzar la colaboraci\u00f3n entre administraciones, empresas y servicios de ocupaci\u00f3n del territorio.<\/p>\n\n<h6 class=\"wp-block-heading\" id=\"h-sobre-la-fira-de-l-ocupacio-girafeina\"><strong>Sobre la feria de la ocupaci\u00f3n GiraFeina<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">La GiraFeina es una iniciativa que conecta personas que buscan trabajo con empresas que tienen vacantes. Ofrece entrevistas r\u00e1pidas, orientaci\u00f3n laboral y talleres para mejorar el curr\u00edculum y las habilidades profesionales. Est\u00e1 dirigida principalmente a personas de 18 a 30 a\u00f1os, pero tambi\u00e9n a cualquier persona que quiera insertarse o progresar en el mercado laboral. La acci\u00f3n se impulsa en el marco del programa Feria Talento Joven, impulsado por la C\u00e1mara de Comercio de Espa\u00f1a y cofinanciado por el Fondo Social Europeo FSE +.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales, reforzando la conexi\u00f3n entre las personas en investigaci\u00f3n de trabajo y el tejido empresarial de la comarca.<\/p>\n","protected":false},"author":7,"featured_media":128193,"parent":0,"template":"","press-release-category":[640],"territorial-chamber":[284],"services-for":[],"solutions-for":[],"location":[],"ppma_author":[806],"class_list":["post-128593","press-release","type-press-release","status-publish","has-post-thumbnail","hentry","press-release-category-notas-de-prensa-servicios","territorial-chamber-garraf-es"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa | Cambra de Comer\u00e7 de Barcelona<\/title>\n<meta name=\"description\" content=\"El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa\" \/>\n<meta property=\"og:description\" content=\"El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/\" \/>\n<meta property=\"og:site_name\" content=\"Cambra de Comer\u00e7 de Barcelona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T10:58:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cambrabcn.org\/wp-content\/uploads\/2026\/05\/GiraFeinaVilanova26_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cambrabcn\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/\"},\"author\":{\"name\":\"Xavier Balsells\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#\\\/schema\\\/person\\\/78150f4b7c36e40679a816a8bfd007c1\"},\"headline\":\"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa\",\"datePublished\":\"2026-05-15T11:13:12+00:00\",\"dateModified\":\"2026-05-20T10:58:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/\"},\"wordCount\":730,\"publisher\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cambrabcn.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GiraFeinaVilanova26_web.jpg\",\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/\",\"url\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/\",\"name\":\"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa | Cambra de Comer\u00e7 de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cambrabcn.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GiraFeinaVilanova26_web.jpg\",\"datePublished\":\"2026-05-15T11:13:12+00:00\",\"dateModified\":\"2026-05-20T10:58:54+00:00\",\"description\":\"El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cambrabcn.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GiraFeinaVilanova26_web.jpg\",\"contentUrl\":\"https:\\\/\\\/cambrabcn.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GiraFeinaVilanova26_web.jpg\",\"width\":1200,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notas de Prensa\",\"item\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/prensa\\\/notas-prensa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/\",\"name\":\"Cambra de Comer\u00e7 de Barcelona\",\"description\":\"La Cambra de Tothom\",\"publisher\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#organization\"},\"alternateName\":\"Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#organization\",\"name\":\"Cambra de Comer\u00e7 de Barcelona\",\"alternateName\":\"Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona\",\"url\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cambrabcn.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-cambra-300x77-1.png\",\"contentUrl\":\"https:\\\/\\\/cambrabcn.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-cambra-300x77-1.png\",\"width\":300,\"height\":77,\"caption\":\"Cambra de Comer\u00e7 de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/cambrabcn\",\"https:\\\/\\\/www.instagram.com\\\/cambrabcn\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/cambrabcn\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PressCambrabcn\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Cambra_Oficial_de_Comer\u00e7,_Ind\u00fastria_i_Navegaci\u00f3_de_Barcelona\",\"http:\\\/\\\/viaf.org\\\/viaf\\\/124017095\"],\"description\":\"La Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona \u00e9s una corporaci\u00f3 de dret p\u00fablic que presta serveis a les empreses, contribuint a la regeneraci\u00f3 del teixit econ\u00f2mic i la creaci\u00f3 d\u2019ocupaci\u00f3.\",\"email\":\"cambra@cambrabcn.cat\",\"telephone\":\"+34 93 416 93 00\",\"legalName\":\"La Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona\",\"foundingDate\":\"1886-01-01\",\"vatID\":\"Q0873001B\",\"taxID\":\"Q0873001B\",\"naics\":\"813910\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cambrabcn.org\\\/es\\\/#\\\/schema\\\/person\\\/78150f4b7c36e40679a816a8bfd007c1\",\"name\":\"Xavier Balsells\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/470ecb8fb93ea8f09ca01b57f8e2fbb21d78607859b93f4d53cab75249ac8d2f?s=96&d=mm&r=g51d22feab2f2326f2e04f757861c21da\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/470ecb8fb93ea8f09ca01b57f8e2fbb21d78607859b93f4d53cab75249ac8d2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/470ecb8fb93ea8f09ca01b57f8e2fbb21d78607859b93f4d53cab75249ac8d2f?s=96&d=mm&r=g\",\"caption\":\"Xavier Balsells\"},\"sameAs\":[\"https:\\\/\\\/cambrabcn.org\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa | Cambra de Comer\u00e7 de Barcelona","description":"El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa","og_description":"El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales.","og_url":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/","og_site_name":"Cambra de Comer\u00e7 de Barcelona","article_modified_time":"2026-05-20T10:58:54+00:00","og_image":[{"width":1200,"height":634,"url":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2026\/05\/GiraFeinaVilanova26_web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cambrabcn","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#article","isPartOf":{"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/"},"author":{"name":"Xavier Balsells","@id":"https:\/\/cambrabcn.org\/es\/#\/schema\/person\/78150f4b7c36e40679a816a8bfd007c1"},"headline":"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa","datePublished":"2026-05-15T11:13:12+00:00","dateModified":"2026-05-20T10:58:54+00:00","mainEntityOfPage":{"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/"},"wordCount":730,"publisher":{"@id":"https:\/\/cambrabcn.org\/es\/#organization"},"image":{"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#primaryimage"},"thumbnailUrl":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2026\/05\/GiraFeinaVilanova26_web.jpg","inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/","url":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/","name":"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa | Cambra de Comer\u00e7 de Barcelona","isPartOf":{"@id":"https:\/\/cambrabcn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#primaryimage"},"image":{"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#primaryimage"},"thumbnailUrl":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2026\/05\/GiraFeinaVilanova26_web.jpg","datePublished":"2026-05-15T11:13:12+00:00","dateModified":"2026-05-20T10:58:54+00:00","description":"El acontecimiento ha permitido realizar m\u00e1s de 1.200 entrevistas de trabajo para cubrir casi 400 vacantes laborales.","breadcrumb":{"@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#primaryimage","url":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2026\/05\/GiraFeinaVilanova26_web.jpg","contentUrl":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2026\/05\/GiraFeinaVilanova26_web.jpg","width":1200,"height":634},{"@type":"BreadcrumbList","@id":"https:\/\/cambrabcn.org\/es\/mes-de-700-persones-participen-en-la-quarta-edicio-de-la-fira-de-locupacio-girafeina-a-vilanova-i-la-geltru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cambrabcn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Notas de Prensa","item":"https:\/\/cambrabcn.org\/es\/prensa\/notas-prensa\/"},{"@type":"ListItem","position":3,"name":"M\u00e1s de 700 personas participan en la cuarta edici\u00f3n de la feria de la ocupaci\u00f3n GiraFeina en Vilanova i la Geltr\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/cambrabcn.org\/es\/#website","url":"https:\/\/cambrabcn.org\/es\/","name":"Cambra de Comer\u00e7 de Barcelona","description":"La Cambra de Tothom","publisher":{"@id":"https:\/\/cambrabcn.org\/es\/#organization"},"alternateName":"Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cambrabcn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cambrabcn.org\/es\/#organization","name":"Cambra de Comer\u00e7 de Barcelona","alternateName":"Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona","url":"https:\/\/cambrabcn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cambrabcn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2023\/11\/logo-cambra-300x77-1.png","contentUrl":"https:\/\/cambrabcn.org\/wp-content\/uploads\/2023\/11\/logo-cambra-300x77-1.png","width":300,"height":77,"caption":"Cambra de Comer\u00e7 de Barcelona"},"image":{"@id":"https:\/\/cambrabcn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cambrabcn","https:\/\/www.instagram.com\/cambrabcn\/","https:\/\/www.linkedin.com\/school\/cambrabcn","https:\/\/www.youtube.com\/user\/PressCambrabcn","https:\/\/ca.wikipedia.org\/wiki\/Cambra_Oficial_de_Comer\u00e7,_Ind\u00fastria_i_Navegaci\u00f3_de_Barcelona","http:\/\/viaf.org\/viaf\/124017095"],"description":"La Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona \u00e9s una corporaci\u00f3 de dret p\u00fablic que presta serveis a les empreses, contribuint a la regeneraci\u00f3 del teixit econ\u00f2mic i la creaci\u00f3 d\u2019ocupaci\u00f3.","email":"cambra@cambrabcn.cat","telephone":"+34 93 416 93 00","legalName":"La Cambra Oficial de Comer\u00e7, Ind\u00fastria, Serveis i Navegaci\u00f3 de Barcelona","foundingDate":"1886-01-01","vatID":"Q0873001B","taxID":"Q0873001B","naics":"813910"},{"@type":"Person","@id":"https:\/\/cambrabcn.org\/es\/#\/schema\/person\/78150f4b7c36e40679a816a8bfd007c1","name":"Xavier Balsells","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/470ecb8fb93ea8f09ca01b57f8e2fbb21d78607859b93f4d53cab75249ac8d2f?s=96&d=mm&r=g51d22feab2f2326f2e04f757861c21da","url":"https:\/\/secure.gravatar.com\/avatar\/470ecb8fb93ea8f09ca01b57f8e2fbb21d78607859b93f4d53cab75249ac8d2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/470ecb8fb93ea8f09ca01b57f8e2fbb21d78607859b93f4d53cab75249ac8d2f?s=96&d=mm&r=g","caption":"Xavier Balsells"},"sameAs":["https:\/\/cambrabcn.org\/"]}]}},"_links":{"self":[{"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/press-release\/128593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":1,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/press-release\/128593\/revisions"}],"predecessor-version":[{"id":128594,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/press-release\/128593\/revisions\/128594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/media\/128193"}],"wp:attachment":[{"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/media?parent=128593"}],"wp:term":[{"taxonomy":"press-release-category","embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/press-release-category?post=128593"},{"taxonomy":"territorial-chamber","embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/territorial-chamber?post=128593"},{"taxonomy":"services-for","embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/services-for?post=128593"},{"taxonomy":"solutions-for","embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/solutions-for?post=128593"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/location?post=128593"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/cambrabcn.org\/es\/wp-json\/wp\/v2\/ppma_author?post=128593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}